{"id":2009,"date":"2021-04-29T11:19:49","date_gmt":"2021-04-29T11:19:49","guid":{"rendered":"https:\/\/www.eliott-markus.com\/wilo\/cookies-attention-aux-nouvelles-regles\/"},"modified":"2023-11-13T14:08:45","modified_gmt":"2023-11-13T14:08:45","slug":"cookies-attention-aux-nouvelles-regles","status":"publish","type":"wilo","link":"https:\/\/www.eliott-markus.com\/en\/wilo\/cookies-attention-aux-nouvelles-regles\/","title":{"rendered":"Cookies : attention aux nouvelles r\u00e8gles\u00a0!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Temps de lecture&nbsp;: 1\u201930<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Depuis le 1<sup>er<\/sup> avril, vous risquez d\u2019\u00eatre sanctionn\u00e9s par la CNIL si votre site ne respecte pas certaines r\u00e8gles relatives <\/strong>        <strong>aux cookies, ces traceurs pistant         l\u2019activit\u00e9  des utilisateurs sur le site et            en dehors.&nbsp;<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Les <a rel=\"noreferrer noopener\" href=\"https:\/\/www.cnil.fr\/fr\/nouvelles-regles-cookies-et-autres-traceurs-bilan-accompagnement-cnil-actions-a-venir\" target=\"_blank\">nouvelles r\u00e8gles de la CNIL<\/a> sur la collecte et le traitement des cookies sont entr\u00e9es en vigueur le 1<sup>er<\/sup> avril. Alors qu\u2019une certaine tol\u00e9rance \u00e9tait exerc\u00e9e depuis l\u2019\u00e9diction des r\u00e8gles le 1<sup>er<\/sup> octobre 2020, la CNIL peut <strong>d\u00e8s \u00e0 pr\u00e9sent effectuer des contr\u00f4les de la conformit\u00e9 des sites<\/strong> et prononcer des <a rel=\"noreferrer noopener\" href=\"https:\/\/www.cnil.fr\/fr\/mission-4-controler-et-sanctionner\" target=\"_blank\">sanctions&nbsp;<\/a>:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; S\u2019ils ne sont pas accept\u00e9s explicitement, les cookies seront consid\u00e9r\u00e9s comme refus\u00e9s,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Les sites doivent offrir la possibilit\u00e9 \u00e0 leurs utilisateurs de refuser ou d\u2019accepter les traceurs tout aussi facilement&nbsp;:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;<em>Le consentement d\u00e9duit de la poursuite de la navigation, qui a longtemps \u00e9t\u00e9 tol\u00e9r\u00e9 par la CNIL (en contradiction d\u2019ailleurs avec les autorit\u00e9s des autres Etats membres), n\u2019est d\u00e9sormais plus admis. Il faut obligatoirement un acte positif clair pour exprimer son consentement.&nbsp;\u00bb<\/em> (Adrien Aulens, associ\u00e9 chez Lighten, Blog <a href=\"https:\/\/blog.predictice.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pr\u00e9dictice<\/a>)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La <strong>mesure d\u2019audience reste autoris\u00e9e<\/strong> et peut \u00eatre consid\u00e9r\u00e9e comme faisant partie des traceurs essentiels au fonctionnement du site et devant donc \u00eatre accept\u00e9s de facto par l\u2019utilisateur. Ces traceurs devront <em>&#8220;\u00eatre strictement limit\u00e9s \u00e0 la seule mesure d&#8217;audience sur le site pour le compte exclusif de l&#8217;\u00e9diteur&#8221;<\/em> ; <em>&#8220;servir uniquement \u00e0 produire des donn\u00e9es statistiques anonymes&#8221; <\/em>; <em>&#8220;ne pas permettre le suivi global de la navigation de la personne utilisant diff\u00e9rentes applications ou naviguant sur diff\u00e9rents sites web&#8221; <\/em>et <em>&#8220;ne pas permettre le recoupement des donn\u00e9es avec d&#8217;autres traitements ou \u00e0 ce que les donn\u00e9es soient transmises \u00e0 des tiers&#8221;<\/em>. <strong>On pourra toujours mesurer la performance des articles ou les pages les plus consult\u00e9es <\/strong>\u00e0 condition de choisir avec pr\u00e9caution sa solution de mesure d\u2019audience, celles-ci n\u2019\u00e9tant pas toutes conformes.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette d\u00e9cision <strong>n\u2019impactera donc que mod\u00e9r\u00e9ment les sites des professionnels des services qui sont tr\u00e8s peu \u00e0 payer pour diffuser des publicit\u00e9s cibl\u00e9es<\/strong> sur les moteurs de recherche\u2026 a contrario des sites B to C&nbsp;: une publicit\u00e9 non cibl\u00e9e leur rapportant 50 % de moins&nbsp;!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Quid des murs de cookies&nbsp;?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Certains sites, tels AlloCin\u00e9, Jeuxvid\u00e9o.com, Marmiton ou 750g estimant que leur mod\u00e8le \u00e9conomique n\u2019est plus viable sans ces cookies, ont mis en place des <em>cookie walls<\/em>&nbsp;: soit l\u2019utilisateur accepte les cookies, soit il paie 2\u20ac pour les refuser et avoir acc\u00e8s au site. Ces murs avaient \u00e9t\u00e9 interdits par la CNIL en 2019, d\u00e9cision annul\u00e9e par le <a href=\"https:\/\/www.conseil-etat.fr\/actualites\/actualites\/le-conseil-d-etat-annule-partiellement-les-lignes-directrices-de-la-cnil-relatives-aux-cookies-et-autres-traceurs-de-connexion\" target=\"_blank\" rel=\"noreferrer noopener\">Conseil d\u2019Etat en 2020<\/a><strong>. La CNIL attend d\u00e9sormais que la situation soit clarifi\u00e9e au niveau europ\u00e9en<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>L\u2019\u00e9mergence d\u2019une conscience utilisateur<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Les utilisateurs sont de plus en plus vigilants quant \u00e0 l\u2019utilisation et la vente de leurs donn\u00e9es mais <em>\u00ab sont heureux de recevoir des publicit\u00e9s et offres de produits qui correspondent r\u00e9ellement \u00e0 leurs besoins \u2013 ils ne veulent pas juste que leurs donn\u00e9es soient collect\u00e9es de mani\u00e8re opaque et vendues au plus offrant. Ils veulent contr\u00f4ler le type d\u2019informations qu\u2019ils partagent et avec qui ils le font&nbsp;\u00bb<\/em> (<a href=\"https:\/\/hbr.org\/2021\/04\/say-goodbye-to-cookies\">Harvard Business Review<\/a>)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les marques sont en train d\u2019\u00e9voluer vers le <em>zero-party data<\/em>, soit une <em>\u00ab&nbsp;information qui est partag\u00e9e de mani\u00e8re intentionnelle et proactive par les consommateurs individuels. Ainsi certaines marques utilisent des sondages, des quizz, des questionnaires, des concours pour collecter des informations tr\u00e8s cibl\u00e9es sur les int\u00e9r\u00eats des utilisateurs&nbsp;\u00bb <\/em>(Ibid)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le temps de la collecte illimit\u00e9e et incontr\u00f4l\u00e9e de donn\u00e9es est termin\u00e9 et ceux qui sauront rassurer les utilisateurs sur ce point gagneront sans doute au change.&nbsp;<\/p>\n","protected":false},"author":11,"featured_media":1254,"template":"","categories":[466],"tags":[158,159,160,121],"class_list":["post-2009","wilo","type-wilo","status-publish","has-post-thumbnail","hentry","category-digital-seo","tag-cnil","tag-cookies","tag-site","tag-site-web"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cookies : attention aux nouvelles r\u00e8gles\u00a0!<\/title>\n<meta name=\"description\" content=\"Depuis le 1er avril, vous risquez d\u2019\u00eatre sanctionn\u00e9s par la CNIL si votre site ne respecte pas certaines r\u00e8gles relatives aux cookies...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eliott-markus.com\/wilo\/cookies-attention-aux-nouvelles-regles\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cookies : attention aux nouvelles r\u00e8gles\u00a0!\" \/>\n<meta property=\"og:description\" content=\"Depuis le 1er avril, vous risquez d\u2019\u00eatre sanctionn\u00e9s par la CNIL si votre site ne respecte pas certaines r\u00e8gles relatives aux cookies...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eliott-markus.com\/wilo\/cookies-attention-aux-nouvelles-regles\/\" \/>\n<meta property=\"og:site_name\" content=\"eliott &amp; markus\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-13T14:08:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eliott-markus.com\/wp-content\/uploads\/2023\/06\/VISUEL-article-42.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"792\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cookies : attention aux nouvelles r\u00e8gles\u00a0!","description":"Depuis le 1er avril, vous risquez d\u2019\u00eatre sanctionn\u00e9s par la CNIL si votre site ne respecte pas certaines r\u00e8gles relatives aux cookies...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eliott-markus.com\/wilo\/cookies-attention-aux-nouvelles-regles\/","og_locale":"en_US","og_type":"article","og_title":"Cookies : attention aux nouvelles r\u00e8gles\u00a0!","og_description":"Depuis le 1er avril, vous risquez d\u2019\u00eatre sanctionn\u00e9s par la CNIL si votre site ne respecte pas certaines r\u00e8gles relatives aux cookies...","og_url":"https:\/\/www.eliott-markus.com\/wilo\/cookies-attention-aux-nouvelles-regles\/","og_site_name":"eliott &amp; markus","article_modified_time":"2023-11-13T14:08:45+00:00","og_image":[{"width":1500,"height":792,"url":"https:\/\/www.eliott-markus.com\/wp-content\/uploads\/2023\/06\/VISUEL-article-42.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eliott-markus.com\/wilo\/cookies-attention-aux-nouvelles-regles\/","url":"https:\/\/www.eliott-markus.com\/wilo\/cookies-attention-aux-nouvelles-regles\/","name":"Cookies : attention aux nouvelles r\u00e8gles\u00a0!","isPartOf":{"@id":"https:\/\/www.eliott-markus.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eliott-markus.com\/wilo\/cookies-attention-aux-nouvelles-regles\/#primaryimage"},"image":{"@id":"https:\/\/www.eliott-markus.com\/wilo\/cookies-attention-aux-nouvelles-regles\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eliott-markus.com\/wp-content\/uploads\/2023\/06\/VISUEL-article-42.jpg","datePublished":"2021-04-29T11:19:49+00:00","dateModified":"2023-11-13T14:08:45+00:00","description":"Depuis le 1er avril, vous risquez d\u2019\u00eatre sanctionn\u00e9s par la CNIL si votre site ne respecte pas certaines r\u00e8gles relatives aux cookies...","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eliott-markus.com\/wilo\/cookies-attention-aux-nouvelles-regles\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.eliott-markus.com\/wilo\/cookies-attention-aux-nouvelles-regles\/#primaryimage","url":"https:\/\/www.eliott-markus.com\/wp-content\/uploads\/2023\/06\/VISUEL-article-42.jpg","contentUrl":"https:\/\/www.eliott-markus.com\/wp-content\/uploads\/2023\/06\/VISUEL-article-42.jpg","width":1500,"height":792},{"@type":"WebSite","@id":"https:\/\/www.eliott-markus.com\/#website","url":"https:\/\/www.eliott-markus.com\/","name":"eliott & markus","description":"","publisher":{"@id":"https:\/\/www.eliott-markus.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eliott-markus.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.eliott-markus.com\/#organization","name":"eliott & markus","url":"https:\/\/www.eliott-markus.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.eliott-markus.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.eliott-markus.com\/wp-content\/uploads\/2023\/06\/cropped-em_fav_2-1.png","contentUrl":"https:\/\/www.eliott-markus.com\/wp-content\/uploads\/2023\/06\/cropped-em_fav_2-1.png","width":512,"height":512,"caption":"eliott & markus"},"image":{"@id":"https:\/\/www.eliott-markus.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.eliott-markus.com\/en\/wp-json\/wp\/v2\/wilo\/2009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eliott-markus.com\/en\/wp-json\/wp\/v2\/wilo"}],"about":[{"href":"https:\/\/www.eliott-markus.com\/en\/wp-json\/wp\/v2\/types\/wilo"}],"author":[{"embeddable":true,"href":"https:\/\/www.eliott-markus.com\/en\/wp-json\/wp\/v2\/users\/11"}],"version-history":[{"count":3,"href":"https:\/\/www.eliott-markus.com\/en\/wp-json\/wp\/v2\/wilo\/2009\/revisions"}],"predecessor-version":[{"id":4510,"href":"https:\/\/www.eliott-markus.com\/en\/wp-json\/wp\/v2\/wilo\/2009\/revisions\/4510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eliott-markus.com\/en\/wp-json\/wp\/v2\/media\/1254"}],"wp:attachment":[{"href":"https:\/\/www.eliott-markus.com\/en\/wp-json\/wp\/v2\/media?parent=2009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eliott-markus.com\/en\/wp-json\/wp\/v2\/categories?post=2009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eliott-markus.com\/en\/wp-json\/wp\/v2\/tags?post=2009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}